{"id":24070,"date":"2024-11-25T07:00:29","date_gmt":"2024-11-25T13:00:29","guid":{"rendered":"https:\/\/borderlessmag.org\/?p=24070"},"modified":"2025-03-13T16:34:37","modified_gmt":"2025-03-13T21:34:37","slug":"el-paso-frontera-reunificacion-de-mascotas-aduana-patrulla-fronteriza-rescate-canino-migrantes","status":"publish","type":"post","link":"https:\/\/borderlessmag.org\/es\/2024\/11\/25\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\/","title":{"rendered":"El rescate de perros en la frontera ayuda a las familias a reunirse con sus mascotas"},"content":{"rendered":"<div id=\"fws_6a57ace37c5ba\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-2 vc_hidden-sm vc_hidden-xs wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col padding-3-percent inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p><span style=\"font-weight: 400;\">Keyla Guti\u00e9rrez lleg\u00f3 a la frontera de El Paso una fr\u00eda ma\u00f1ana de finales de marzo. Tras cruzar nueve pa\u00edses, lleg\u00f3 por fin a suelo estadounidense a las 5 de la ma\u00f1ana. Estaba agotada, pero enseguida sinti\u00f3 un alivio abrumador.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Guti\u00e9rrez y su familia hab\u00edan pasado cinco meses viajando desde Ecuador para pedir asilo en Estados Unidos. Sus perros, Tobby y Luna, hab\u00edan hecho el traicionero viaje con ellos, y ahora todos estar\u00edan a salvo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero la sensaci\u00f3n de alivio de Guti\u00e9rrez se apag\u00f3 cuando un agente de la Patrulla de Aduanas y Fronteras (CBP) le dijo que tendr\u00eda que dejar a sus perros en el desierto si quer\u00edan permanecer en Estados Unidos.\u00a0<\/span><\/p>\n<\/div>\n\n\n\n<div class=\"templatera_shortcode\">\n\t\t<div id=\"fws_6a57ace37dcb5\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle small\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone border_color_909090 border_style_solid\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t<div id=\"fws_6a57ace37ea2c\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle large top_margin_20px bottom_margin_20px\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"true\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background: #FFFFFF; background: linear-gradient(90deg,#FFFFFF 0%,#FFFFFF 100%);  opacity: 1; \"><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col padding-3-percent force-phone-text-align-center inherit_tablet inherit_phone border_top_desktop_1px border_bottom_desktop_1px border_color_FFFFFF border_style_solid\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a57ace37f0ed\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-7 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<h4 id=\"news-that-puts-power-under-the-spotlight-and-communities-at-the-center\"><strong>Noticias que ponen el poder en el punto de mira y a las comunidades en el centro.<\/strong><\/h4>\n<p>Suscr\u00edbase a nuestro bolet\u00edn gratuito y reciba actualizaciones dos veces por semana.<\/p>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div style=\"margin-top: -20px; \" class=\"vc_col-sm-5 wpb_column column_container vc_column_container col child_column neg-marg no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"_form_1\"><\/div><script src=\"https:\/\/borderlessmag.bluelena.io\/f\/embed.php?id=1\" charset=\"utf-8\"><\/script>\n\t\t<\/div>\n\t<\/div>\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p><span style=\"font-weight: 400;\">\"Los perros llevaban tanto tiempo con nosotros que eran como ni\u00f1os para m\u00ed\", dice Guti\u00e9rrez. \"No hab\u00eda forma de abandonarlos. Eran literalmente todo mi hogar: los ni\u00f1os y los perros\".\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tras algunas idas y venidas, el agente del CBP dijo que se pondr\u00edan en contacto con un cuidador del perro.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A\u00fan sin saber ad\u00f3nde ir\u00edan los perros, Guti\u00e9rrez y sus hijos esperaron durante seis horas hasta que lleg\u00f3 un hombre y se llev\u00f3 a sus perros a un refugio para que esperaran mientras los agentes fronterizos procesaban a su familia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La familia fue puesta en libertad al d\u00eda siguiente de su examen de asilo y llevada al refugio a recoger a sus perros. A\u00fan as\u00ed, sin un lugar adonde ir, pidi\u00f3 ayuda al refugio de animales para sus queridas mascotas. Fue entonces cuando Guti\u00e9rrez conoci\u00f3 a Ruby Montana, propietaria de Bridge Pups Rescue.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Montana y los voluntarios de Bridge Pups Rescue han pasado los dos \u00faltimos a\u00f1os reuniendo a inmigrantes con sus mascotas que no pueden permanecer con ellos mientras est\u00e1n retenidos por el CBP.<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Montana puso en marcha el rescate de animales en 2012, despu\u00e9s de que su hermano, agente de la patrulla fronteriza, le contara cu\u00e1ntos animales vagabundos ve\u00eda a lo largo de la frontera. Desde entonces, los agentes fronterizos llaman a Montana para avisarle cuando encuentran un perro callejero, y ella colabora con voluntarios para acoger y encontrar hogares para las mascotas.\u00a0<\/span><\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 vc_hidden-sm vc_hidden-xs wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a57ace380eda\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row article-image\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <img decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1080\" width=\"1616\" data-animation=\"fade-in\" src=\"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_03.jpg\" alt=\"\" srcset=\"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_03.jpg 1616w, https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_03-1536x1027.jpg 1536w, https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_03-150x100.jpg 150w, https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_03-240x160.jpg 240w, https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_03-300x200.jpg 300w, https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_03-600x400.jpg 600w, https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_03-900x600.jpg 900w, https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_03-898x600.jpg 898w, https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_03-1242x830.jpg 1242w, https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_03-768x513.jpg 768w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n         <\/div>\r\n      <\/div><span class=\"vc_figure-caption ccfic-text media-caption\">Ruby Montana a lo largo de la frontera entre EE.UU. y M\u00e9xico.<\/span><span class=\"media-credit\">Foto de Richard Gonzalez<\/span><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a57ace381e37\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-2 vc_hidden-sm vc_hidden-xs wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col padding-3-percent inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p><span style=\"font-weight: 400;\">El trabajo de Montana ha evolucionado a lo largo de la \u00faltima d\u00e9cada. En el verano de 2022, un agente de la patrulla fronteriza se puso en contacto con Montana acerca de una familia de inmigrantes que hab\u00eda cruzado la frontera con su perro llamado Simba. Ella acept\u00f3 ayudar inmediatamente y, desde entonces, ayuda a acoger temporalmente y reunir a las mascotas con los reci\u00e9n llegados que cruzan la frontera entre Estados Unidos y M\u00e9xico.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Montana, profesora de Humanidades y Estudios Chicanos en la Universidad de Texas en El Paso, procede de una familia de inmigrantes. Sus abuelos se trasladaron de Chihuahua a El Paso en los a\u00f1os 50 en busca de una vida mejor para sus padres y nietos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"Estoy muy agradecido por lo que han hecho y por todo lo que han luchado por nosotros\", dijo Montana. \"Y creo que esa es la parte humana, \u00bfverdad? Todos queremos lo mejor para nuestras familias, para nosotros mismos y para nuestras mascotas\".<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Humanizar la experiencia del inmigrante -especialmente ante personas que de otro modo carecer\u00edan de compasi\u00f3n por su situaci\u00f3n- es una parte importante de la misi\u00f3n de Bridge Pups Rescue.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"Ven su propio amor por sus mascotas reflejado en lo mucho que estos inmigrantes quieren tambi\u00e9n a sus mascotas, y creo que eso es algo que realmente puede unir a mucha gente\".<\/span><\/p>\n<\/div>\n\n\n\n<div id=\"fws_6a57ace3828eb\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone border_bottom_desktop_1px border_color_000000 border_style_solid\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_sep_color_black wpb_content_element vc_separator-has-text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><h4 id=\"read-more-of-our-coverage\">M\u00e1s informaci\u00f3n<\/h4><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t\t\t<div class=\"pk-inline-posts\">\n\t\t\t\n\t\t\t<div class=\"pk-inline-posts-container pk-inline-posts-template-list\"\n\t\t\t\tdata-columns=\"1\">\n\t\t\t\t\t\t<article id=\"post-24008\" class=\"post-24008 post type-post status-publish format-standard has-post-thumbnail category-as-told-to category-visuals tag-ipreportraits\">\n\t\t\t<div class=\"pk-post-outer\">\n\n\t\t\t\t\t\t\t\t<div class=\"pk-post-inner\">\n\t\t\t\t\t<div class=\"entry-thumbnail\">\n\t\t\t\t\t\t<div class=\"pk-overlay pk-overlay-ratio pk-ratio-landscape\">\n\t\t\t\t\t\t\t<div class=\"pk-overlay-background\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/borderlessmag.org\/es\/2024\/11\/19\/leaving-venezuela-the-only-option-for-us-was-the-united-states-migrants-new-arrivals\/\" class=\"pk-overlay-link\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_10_28_Migrant-Portraits_IPRE_Lead-300x225.jpg\" class=\"attachment-pk-thumbnail size-pk-thumbnail wp-post-image\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"pk-post-inner\">\n\t\t\t\t\t<header>\n\t\t\t\t\t\t<h3 class=\"pk-title\"><a href=\"https:\/\/borderlessmag.org\/es\/2024\/11\/19\/leaving-venezuela-the-only-option-for-us-was-the-united-states-migrants-new-arrivals\/\" rel=\"bookmark\">Abandonar Venezuela: \"La \u00fanica opci\u00f3n para nosotros era Estados Unidos<\/a><\/h3>\t\t\t\t\t\t\t<div class=\"pk-post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"pk-meta-author meta-author\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/borderlessmag.org\/es\/author\/jonathan-torres\/\" title=\"Ver todas las entradas de Jonathan Torres, Martha Contreras\">Jonathan Torres, Martha Contreras<\/a><\/span><\/span>\t\t\t\t\t\t\t\t<span class=\"sep\">-<\/span>\n\t\t\t\t\t\t\t\t<span class=\"pk-meta-date meta-date\"><a href=\"https:\/\/borderlessmag.org\/es\/2024\/11\/19\/leaving-venezuela-the-only-option-for-us-was-the-united-states-migrants-new-arrivals\/\" rel=\"bookmark\">19 de noviembre de 2024<\/a><\/span>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/header><!-- .entry-header -->\n\t\t\t\t<\/div><!-- .post-inner -->\n\n\t\t\t<\/div><!-- .post-outer -->\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p><span style=\"font-weight: 400;\">Desde 2022, Montana ha trabajado con algo m\u00e1s de 20 hogares de acogida para reunir a casi 40 mascotas con sus familias en todo el pa\u00eds. Los voluntarios de Bridge Pups cuidan de los perros mientras est\u00e1n separados de sus due\u00f1os, proporcion\u00e1ndoles atenci\u00f3n veterinaria, las vacunas necesarias y comida. A menudo pasan varios meses hasta que se re\u00fanen con sus due\u00f1os. Los voluntarios tambi\u00e9n transportan a los perros a sus nuevos hogares una vez que sus due\u00f1os se han instalado. A veces estos nuevos hogares est\u00e1n a cientos de kil\u00f3metros de distancia o al final de la calle.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Montana ha certificado recientemente a Bridge Pups Rescue como organizaci\u00f3n sin \u00e1nimo de lucro y est\u00e1 trabajando con una congresista local y la <\/span><a href=\"https:\/\/www.txcivilrights.org\/\"><span style=\"font-weight: 400;\">Proyecto de Derechos Civiles de Texas<\/span><\/a><span style=\"font-weight: 400;\"> para establecer una pol\u00edtica federal que permita a los inmigrantes entrar en el pa\u00eds con sus mascotas. En la actualidad, los agentes de la Patrulla Fronteriza y de la Guardia Nacional de Texas tienen discrecionalidad para decidir si se permite que un perro cruce con una familia, lo que ha dado lugar a <\/span><a href=\"https:\/\/www.ktsm.com\/news\/migrant-family-seek-help-locating-stolen-pup\/amp\/\"><span style=\"font-weight: 400;\">perros perdidos e incluso robados<\/span><\/a><span style=\"font-weight: 400;\">dijo Montana.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"Ha habido varios perros que han desaparecido por completo, y me siento absolutamente impotente, sobre todo sabiendo cu\u00e1nto se han sacrificado estas personas para llegar hasta aqu\u00ed\", dijo Montana.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"No compruebo la nacionalidad de un perro antes de mostrar compasi\u00f3n por \u00e9l, y lo mismo ocurre con los humanos\", afirma.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La misi\u00f3n de Bridge Pups Rescue ha sido una bendici\u00f3n para las familias inmigrantes que esperan empezar una nueva vida en Estados Unidos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mientras Guti\u00e9rrez y sus tres hijos recorr\u00edan los refugios hasta llegar a su hogar permanente en Wisconsin, les consolaba saber que sus perros estaban al cuidado de las amables personas de Bridge Pups.\u00a0<\/span><\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 vc_hidden-sm vc_hidden-xs wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t<div class=\"wpb_widgetised_column wpb_content_element\">\n\t\t<div id=\"sidebar\" data-nectar-ss=\"true\" class=\"wpb_wrapper\">\n\t\t\t<div id=\"custom_html-4 1articleright\" class=\"widget_text widget widget_custom_html\"><h3 id=\"wordpress-popular-posts\" class=\"widget-title\">Entradas populares de WordPress<\/h3><div class=\"textwidget custom-html-widget\"><h4 id=\"trending-posts\" class=\"widget-title\">Tendencias<\/h4><div class=\"wpp-shortcode\"><script type=\"application\/json\" data-id=\"wpp-shortcode-inline-js\">{\"title\":\"Trending Posts\",\"limit\":\"3\",\"offset\":0,\"range\":\"custom\",\"time_quantity\":\"124\",\"time_unit\":\"day\",\"freshness\":\"1\",\"order_by\":\"views\",\"post_type\":\"post\",\"pid\":\"\",\"exclude\":\"\",\"cat\":\"\",\"taxonomy\":\"category\",\"term_id\":\"\",\"author\":\"\",\"shorten_title\":{\"active\":false,\"length\":0,\"words\":false},\"post-excerpt\":{\"active\":false,\"length\":0,\"keep_format\":false,\"words\":false},\"thumbnail\":{\"active\":true,\"build\":\"predefined\",\"width\":\"240\",\"height\":\"160\"},\"rating\":false,\"stats_tag\":{\"comment_count\":false,\"views\":false,\"author\":false,\"date\":{\"active\":false,\"format\":\"F j, Y\"},\"category\":false,\"taxonomy\":{\"active\":false,\"name\":\"category\"}},\"markup\":{\"custom_html\":true,\"wpp-start\":\"&lt;ul class=&quot;wpp-list wpp-cardview&quot;&gt;\",\"wpp-end\":\"&lt;\\\/ul&gt;\",\"title-start\":\"&lt;h4 class=&quot;widget-title&quot;&gt;\",\"title-end\":\"&lt;\\\/h4&gt;\",\"post-html\":\"&lt;li&gt;{thumb} {title} {stats}&lt;\\\/li&gt;\"},\"theme\":{\"name\":\"\"}}<\/script><div class=\"wpp-shortcode-placeholder\"><\/div><\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a57ace387a06\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row article-image\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <img decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1079\" width=\"1439\" data-animation=\"fade-in\" src=\"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_02.jpg\" alt=\"\" srcset=\"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_02.jpg 1439w, https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_02-300x225.jpg 300w, https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_02-800x600.jpg 800w, https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_02-1107x830.jpg 1107w, https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-Bridge-Pups_02-768x576.jpg 768w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n         <\/div>\r\n      <\/div><span class=\"vc_figure-caption ccfic-text media-caption\">Primera imagen: Los hijos de Keyla Guti\u00e9rrez, Tatiana, de 14 a\u00f1os, Karla, de 16, y Alejandro, de 15, con sus perros Luna y Tobby. Segunda imagen: Keyla Guti\u00e9rrez sentada con sus perros Tobby y Luna en el r\u00edo Wisconsin. <\/span><span class=\"media-credit\">Fotos cortes\u00eda de Keyla Gutierrez<\/span><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a57ace388783\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-2 vc_hidden-sm vc_hidden-xs wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col padding-3-percent inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p><span style=\"font-weight: 400;\">El estado exigi\u00f3 que Tobby fuera esterilizado, por lo que un voluntario facilit\u00f3 la operaci\u00f3n y obtuvo la documentaci\u00f3n legal necesaria para que los perros permanecieran en EE.UU. Cuando Guti\u00e9rrez finalmente se instal\u00f3 tras cinco meses, uno de los voluntarios recorri\u00f3 casi 1.500 millas para reunir a los perros con su familia.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"No dej\u00e1bamos de pensar en lo que iba a pasar, imaginando que no \u00edbamos a volver a verlos\", dijo Guti\u00e9rrez. \"As\u00ed que fue una bendici\u00f3n; ni siquiera puedo explicar c\u00f3mo me sent\u00ed en ese momento\".<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tras meses separados, a Guti\u00e9rrez y a sus hijos se les saltaron las l\u00e1grimas cuando pudieron volver a abrazar a sus perros. \"Fue como haber encontrado a nuestro amigo perdido\", dijo Guti\u00e9rrez. \"Los ni\u00f1os me preguntaban si cre\u00eda que los perros se hab\u00edan olvidado de nosotros, pero ahora es como si los meses no hubieran pasado\".<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">Para apoyar a Bridge Pups Rescue, <\/span><\/i><a href=\"https:\/\/www.paypal.com\/donate\/?hosted_button_id=U5GM2Z5MPLMLJ\"><i><span style=\"font-weight: 400;\">puede donar aqu\u00ed<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">.<\/span><\/i><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">Chelsea Verstegen es redactora colaboradora y reportera de Borderless Magazine.\u00a0<\/span><\/i><\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 vc_hidden-sm vc_hidden-xs wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Los voluntarios de Bridge Pups Rescue, con sede en El Paso y dirigidos por Ruby Montana, han reunido a inmigrantes con sus mascotas tras cruzar la frontera entre Estados Unidos y M\u00e9xico.<\/p>","protected":false},"author":28,"featured_media":24065,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[667],"coauthors":[206],"class_list":{"0":"post-24070","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-immigration-policy","8":"tag-elpaso"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El Paso Dog Rescue is Reuniting Migrants with Pets Nationwide &#8211; Borderless Magazine NFP<\/title>\n<meta name=\"description\" content=\"Over the last two years, Bridge Pups Rescue, led by Ruby Montana, has been reuniting immigrants crossing the US-Mexico border.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/borderlessmag.org\/es\/2024\/11\/25\/el-paso-frontera-reunificacion-de-mascotas-aduana-patrulla-fronteriza-rescate-canino-migrantes\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How a Dog Rescue at the Border is Helping Families Reunite with Their Pets &#8211; Borderless Magazine NFP\" \/>\n<meta property=\"og:description\" content=\"How a Dog Rescue at the Border is Helping Families Reunite with Their Pets &#8211; Borderless Magazine NFP\" \/>\n<meta property=\"og:url\" content=\"https:\/\/borderlessmag.org\/es\/2024\/11\/25\/el-paso-frontera-reunificacion-de-mascotas-aduana-patrulla-fronteriza-rescate-canino-migrantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Borderless Magazine NFP\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BorderlessMagazine\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-25T13:00:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-13T21:34:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-BridgePups_Feature.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jonathan Torres, Martha Contreras\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chelsea Verstegen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Jonathan Torres, Martha Contreras\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/2024\\\/11\\\/25\\\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/2024\\\/11\\\/25\\\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\\\/\"},\"author\":{\"name\":\"Chelsea Verstegen\",\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#\\\/schema\\\/person\\\/20ac2779216294471760bd1f973a2e26\"},\"headline\":\"How a Dog Rescue at the Border is Helping Families Reunite with Their Pets\",\"datePublished\":\"2024-11-25T13:00:29+00:00\",\"dateModified\":\"2025-03-13T21:34:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/2024\\\/11\\\/25\\\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\\\/\"},\"wordCount\":2683,\"publisher\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/2024\\\/11\\\/25\\\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borderlessmag.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/2024_11_21-BridgePups_Feature.jpg\",\"keywords\":[\"Elpaso\"],\"articleSection\":[\"Immigration Policy\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/es\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/2024\\\/11\\\/25\\\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\\\/\",\"url\":\"https:\\\/\\\/borderlessmag.org\\\/2024\\\/11\\\/25\\\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\\\/\",\"name\":\"El Paso Dog Rescue is Reuniting Migrants with Pets Nationwide &#8211; Borderless Magazine NFP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/2024\\\/11\\\/25\\\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/2024\\\/11\\\/25\\\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borderlessmag.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/2024_11_21-BridgePups_Feature.jpg\",\"datePublished\":\"2024-11-25T13:00:29+00:00\",\"dateModified\":\"2025-03-13T21:34:37+00:00\",\"description\":\"Over the last two years, Bridge Pups Rescue, led by Ruby Montana, has been reuniting immigrants crossing the US-Mexico border.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/borderlessmag.org\\\/2024\\\/11\\\/25\\\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/2024\\\/11\\\/25\\\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\\\/#primaryimage\",\"url\":\"https:\\\/\\\/borderlessmag.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/2024_11_21-BridgePups_Feature.jpg\",\"contentUrl\":\"https:\\\/\\\/borderlessmag.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/2024_11_21-BridgePups_Feature.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#website\",\"url\":\"https:\\\/\\\/borderlessmag.org\\\/\",\"name\":\"Borderless Magazine NFP\",\"description\":\"Stories about immigration and immigrants\",\"publisher\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#organization\"},\"alternateName\":\"Borderless\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/borderlessmag.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#organization\",\"name\":\"Borderless Magazine NFP\",\"alternateName\":\"Borderless Mag\",\"url\":\"https:\\\/\\\/borderlessmag.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/borderlessmag.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/BorderlessLogo_main_square.jpg\",\"contentUrl\":\"https:\\\/\\\/borderlessmag.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/BorderlessLogo_main_square.jpg\",\"width\":696,\"height\":696,\"caption\":\"Borderless Magazine NFP\"},\"image\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BorderlessMagazine\",\"https:\\\/\\\/www.instagram.com\\\/borderless_mag\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@borderless_mag\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#\\\/schema\\\/person\\\/20ac2779216294471760bd1f973a2e26\",\"name\":\"Chelsea Verstegen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e257c3f988d4002ac9ef8c7ea77408486c056287741d0d8eac43596fb176a6f?s=96&d=mm&r=g6bc2f92c101eb4417ab1dd5d6e08d348\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e257c3f988d4002ac9ef8c7ea77408486c056287741d0d8eac43596fb176a6f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e257c3f988d4002ac9ef8c7ea77408486c056287741d0d8eac43596fb176a6f?s=96&d=mm&r=g\",\"caption\":\"Chelsea Verstegen\"},\"url\":\"https:\\\/\\\/borderlessmag.org\\\/es\\\/author\\\/chelsea-verstegen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El Paso Dog Rescue re\u00fane a migrantes con sus mascotas en todo el pa\u00eds - Borderless Magazine NFP","description":"Durante los dos \u00faltimos a\u00f1os, Bridge Pups Rescue, dirigida por Ruby Montana, ha reunido a inmigrantes que cruzaban la frontera entre Estados Unidos y M\u00e9xico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/borderlessmag.org\/es\/2024\/11\/25\/el-paso-frontera-reunificacion-de-mascotas-aduana-patrulla-fronteriza-rescate-canino-migrantes\/","og_locale":"es_MX","og_type":"article","og_title":"How a Dog Rescue at the Border is Helping Families Reunite with Their Pets &#8211; Borderless Magazine NFP","og_description":"How a Dog Rescue at the Border is Helping Families Reunite with Their Pets &#8211; Borderless Magazine NFP","og_url":"https:\/\/borderlessmag.org\/es\/2024\/11\/25\/el-paso-frontera-reunificacion-de-mascotas-aduana-patrulla-fronteriza-rescate-canino-migrantes\/","og_site_name":"Borderless Magazine NFP","article_publisher":"https:\/\/www.facebook.com\/BorderlessMagazine","article_published_time":"2024-11-25T13:00:29+00:00","article_modified_time":"2025-03-13T21:34:37+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-BridgePups_Feature.jpg","type":"image\/jpeg"}],"author":"Jonathan Torres, Martha Contreras","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Chelsea Verstegen","Tiempo de lectura":"13 minutos","Written by":"Jonathan Torres, Martha Contreras"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/borderlessmag.org\/2024\/11\/25\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\/#article","isPartOf":{"@id":"https:\/\/borderlessmag.org\/2024\/11\/25\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\/"},"author":{"name":"Chelsea Verstegen","@id":"https:\/\/borderlessmag.org\/#\/schema\/person\/20ac2779216294471760bd1f973a2e26"},"headline":"How a Dog Rescue at the Border is Helping Families Reunite with Their Pets","datePublished":"2024-11-25T13:00:29+00:00","dateModified":"2025-03-13T21:34:37+00:00","mainEntityOfPage":{"@id":"https:\/\/borderlessmag.org\/2024\/11\/25\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\/"},"wordCount":2683,"publisher":{"@id":"https:\/\/borderlessmag.org\/#organization"},"image":{"@id":"https:\/\/borderlessmag.org\/2024\/11\/25\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\/#primaryimage"},"thumbnailUrl":"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-BridgePups_Feature.jpg","keywords":["Elpaso"],"articleSection":["Immigration Policy"],"inLanguage":"es","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/borderlessmag.org\/es\/#organization"}},{"@type":"WebPage","@id":"https:\/\/borderlessmag.org\/2024\/11\/25\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\/","url":"https:\/\/borderlessmag.org\/2024\/11\/25\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\/","name":"El Paso Dog Rescue re\u00fane a migrantes con sus mascotas en todo el pa\u00eds - Borderless Magazine NFP","isPartOf":{"@id":"https:\/\/borderlessmag.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/borderlessmag.org\/2024\/11\/25\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\/#primaryimage"},"image":{"@id":"https:\/\/borderlessmag.org\/2024\/11\/25\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\/#primaryimage"},"thumbnailUrl":"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-BridgePups_Feature.jpg","datePublished":"2024-11-25T13:00:29+00:00","dateModified":"2025-03-13T21:34:37+00:00","description":"Durante los dos \u00faltimos a\u00f1os, Bridge Pups Rescue, dirigida por Ruby Montana, ha reunido a inmigrantes que cruzaban la frontera entre Estados Unidos y M\u00e9xico.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/borderlessmag.org\/2024\/11\/25\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/borderlessmag.org\/2024\/11\/25\/el-paso-border-pet-reunification-custom-border-patrol-dog-rescue-migrants\/#primaryimage","url":"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-BridgePups_Feature.jpg","contentUrl":"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2024\/11\/2024_11_21-BridgePups_Feature.jpg","width":1920,"height":1280},{"@type":"WebSite","@id":"https:\/\/borderlessmag.org\/#website","url":"https:\/\/borderlessmag.org\/","name":"Revista Borderless NFP","description":"Historias sobre inmigraci\u00f3n e inmigrantes","publisher":{"@id":"https:\/\/borderlessmag.org\/#organization"},"alternateName":"Borderless","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/borderlessmag.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/borderlessmag.org\/#organization","name":"Revista Borderless NFP","alternateName":"Borderless Mag","url":"https:\/\/borderlessmag.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/borderlessmag.org\/#\/schema\/logo\/image\/","url":"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2025\/08\/BorderlessLogo_main_square.jpg","contentUrl":"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2025\/08\/BorderlessLogo_main_square.jpg","width":696,"height":696,"caption":"Borderless Magazine NFP"},"image":{"@id":"https:\/\/borderlessmag.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BorderlessMagazine","https:\/\/www.instagram.com\/borderless_mag\/","https:\/\/www.tiktok.com\/@borderless_mag"]},{"@type":"Person","@id":"https:\/\/borderlessmag.org\/#\/schema\/person\/20ac2779216294471760bd1f973a2e26","name":"Chelsea Verstegen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0e257c3f988d4002ac9ef8c7ea77408486c056287741d0d8eac43596fb176a6f?s=96&d=mm&r=g6bc2f92c101eb4417ab1dd5d6e08d348","url":"https:\/\/secure.gravatar.com\/avatar\/0e257c3f988d4002ac9ef8c7ea77408486c056287741d0d8eac43596fb176a6f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e257c3f988d4002ac9ef8c7ea77408486c056287741d0d8eac43596fb176a6f?s=96&d=mm&r=g","caption":"Chelsea Verstegen"},"url":"https:\/\/borderlessmag.org\/es\/author\/chelsea-verstegen\/"}]}},"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/posts\/24070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/comments?post=24070"}],"version-history":[{"count":3,"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/posts\/24070\/revisions"}],"predecessor-version":[{"id":24074,"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/posts\/24070\/revisions\/24074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/media\/24065"}],"wp:attachment":[{"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/media?parent=24070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/categories?post=24070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/tags?post=24070"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/coauthors?post=24070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}