{"id":19346,"date":"2023-06-05T10:27:30","date_gmt":"2023-06-05T15:27:30","guid":{"rendered":"https:\/\/borderlessmag.org\/?p=19346"},"modified":"2025-10-08T09:04:29","modified_gmt":"2025-10-08T14:04:29","slug":"inmigrantes-negros-hoy-max-senegal-marruecos","status":"publish","type":"post","link":"https:\/\/borderlessmag.org\/es\/2023\/06\/05\/black-immigrants-today-max-senegal-morocco\/","title":{"rendered":"Max"},"content":{"rendered":"<div id=\"fws_6a97d24cc73b6\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-2 vc_hidden-sm vc_hidden-xs wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col padding-3-percent inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p><em>Estimaciones de Pew Research <a href=\"https:\/\/www.pewresearch.org\/race-ethnicity\/2022\/01\/20\/one-in-ten-black-people-living-in-the-u-s-are-immigrants\/\">1 de cada 10 negros en Estados Unidos es inmigrante<\/a>. En <a href=\"https:\/\/borderlessmag.org\/es\/categoria\/inmigrantes-negros-hoy\/\">Inmigrantes negros hoy<\/a>Borderless Magazine habl\u00f3 con inmigrantes negros de Chicago sobre sus hogares, sus vidas y los retos a los que se enfrentaron al llegar a Estados Unidos.<\/em><\/p>\n<p><em>Nota de la Redacci\u00f3n: <\/em><br \/>\n<em>*Max ha optado por utilizar un seud\u00f3nimo para proteger su seguridad y privacidad.<\/em><br \/>\n<em>**Este art\u00edculo contiene informaci\u00f3n sobre agresiones y\/o violencia sexual. \u00bfNecesitas hablar con alguien? Llame a la l\u00ednea directa de crisis por violaci\u00f3n del \u00e1rea de Chicago al 888-293-2080.<br \/>\n*** Esta historia ha sido editada por razones de longitud y claridad.<\/em><\/p>\n<\/div>\n\n\n\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_30 vc_sep_pos_align_center vc_sep_color_black wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p>Max* nunca plane\u00f3 venir a EE.UU.<\/p>\n<p>Naci\u00f3 y creci\u00f3 en <a href=\"https:\/\/www.hrw.org\/africa\/senegal\">Dakar, Senegal<\/a>. Pero tras a\u00f1os de sufrir penurias econ\u00f3micas y abusos sexuales, fue expulsado de su familia y su comunidad. Su familia le impidi\u00f3 denunciar a la polic\u00eda para evitar encarcelar a su agresor -otro miembro de la familia- y ser estigmatizado en su comunidad. Finalmente, un t\u00edo le ayud\u00f3 a escapar a Marruecos en 2016.<\/p>\n<\/div>\n\n\n\n<div class=\"templatera_shortcode\">\n\t\t<div id=\"fws_6a97d24cc8310\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle small\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone border_color_909090 border_style_solid\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t<div id=\"fws_6a97d24cc875b\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle large top_margin_20px bottom_margin_20px\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"true\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background: #FFFFFF; background: linear-gradient(90deg,#FFFFFF 0%,#FFFFFF 100%);  opacity: 1; \"><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col padding-3-percent force-phone-text-align-center inherit_tablet inherit_phone border_top_desktop_1px border_bottom_desktop_1px border_color_FFFFFF border_style_solid\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a97d24cc8946\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-7 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<h4 id=\"news-that-puts-power-under-the-spotlight-and-communities-at-the-center\"><strong>Noticias que ponen el poder en el punto de mira y a las comunidades en el centro.<\/strong><\/h4>\n<p>Suscr\u00edbase a nuestro bolet\u00edn gratuito y reciba actualizaciones dos veces por semana.<\/p>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div style=\"margin-top: -20px; \" class=\"vc_col-sm-5 wpb_column column_container vc_column_container col child_column neg-marg no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"_form_1\"><\/div><script src=\"https:\/\/borderlessmag.bluelena.io\/f\/embed.php?id=1\" charset=\"utf-8\"><\/script>\n\t\t<\/div>\n\t<\/div>\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p>Empezar de nuevo en Marruecos trajo consigo nuevos retos e incluso nuevas traiciones. Cuando Max necesit\u00f3 ayuda, acudi\u00f3 a <a href=\"https:\/\/www.unhcr.org\/en-us\/\">el Alto Comisionado de las Naciones Unidas para los Refugiados<\/a> (ACNUR), que facilit\u00f3 su traslado a Estados Unidos en 2020.<\/p>\n<p>Max habl\u00f3 con Borderless sobre los abusos de los que escap\u00f3 en Senegal, los retos a los que se enfrent\u00f3 en Marruecos y la esperanza que le impulsa ahora.<\/p>\n<\/div>\n\n\n\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_30 vc_sep_pos_align_center vc_sep_color_black wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p>Nac\u00ed y crec\u00ed en la Rep\u00fablica de Senegal, en \u00c1frica Occidental. Mi difunta madre -falleci\u00f3 el a\u00f1o pasado- era alcoh\u00f3lica y ten\u00eda problemas de salud mental. Mi \u00fanico hermano se hizo drogadicto y alcoh\u00f3lico muy joven. La cantidad de drogas y alcohol que consume al d\u00eda es incalculable.<\/p>\n<p>Cuando estaba en el primer ciclo de secundaria, mi hermano fue a la c\u00e1rcel por violar a alguien. Despu\u00e9s de eso, dej\u00e9 de ir a la escuela para poder trabajar y mantener a mi madre. Cuando mi hermano sali\u00f3 de la c\u00e1rcel, su comportamiento abusivo hacia mi madre y hacia m\u00ed se aceler\u00f3 exponencialmente. Cada vez que ped\u00eda dinero para drogas y no lo consegu\u00eda, abusaba de mi madre y de m\u00ed. Mi hermano estaba fuera de control.<\/p>\n<p>Mi hermano me trataba como a una esclava. Yo era su sost\u00e9n y el de mi madre. Trabajaba en las granjas de la gente y vend\u00eda sus productos en el mercado para poder ganar dinero y mantener a la familia. Adem\u00e1s de aprovecharse de m\u00ed por dinero, mi hermano empez\u00f3 a agredirme sexualmente.<\/p>\n<p>Una noche volvi\u00f3 de la ciudad, ebrio como de costumbre. Estaba a punto de dormirme cuando me di cuenta de que alguien me estaba tocando. Me sent\u00ed inc\u00f3moda, pero \u00e9l me dijo que no me preocupara y que todo ir\u00eda bien. Era la primera vez que mi hermano me forzaba. Me amenaz\u00f3 y me dijo que no gritara. Me apret\u00f3 la boca para que no gritara. Estaba aterrorizada y sollozaba mientras me sujetaba la boca y me violaba. Esto me pas\u00f3 muchas veces, pero ten\u00eda miedo de cont\u00e1rselo a alguien.<\/p>\n<p>Habl\u00e9 con mi madre de los malos tratos, pero nunca tom\u00f3 medidas para ayudarme, quiz\u00e1 por sus problemas mentales o por miedo a mi hermano.<\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 vc_hidden-sm vc_hidden-xs wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t<div class=\"wpb_widgetised_column wpb_content_element\">\n\t\t<div id=\"sidebar\" data-nectar-ss=\"true\" class=\"wpb_wrapper\">\n\t\t\t<div id=\"custom_html-4 1articleright\" class=\"widget_text widget widget_custom_html\"><h3 id=\"wordpress-popular-posts\" class=\"widget-title\">Entradas populares de WordPress<\/h3><div class=\"textwidget custom-html-widget\"><h4 id=\"trending-posts\" class=\"widget-title\">Tendencias<\/h4><div class=\"wpp-shortcode\"><script type=\"application\/json\" data-id=\"wpp-shortcode-inline-js\">{\"title\":\"Trending Posts\",\"limit\":\"3\",\"offset\":0,\"range\":\"custom\",\"time_quantity\":\"124\",\"time_unit\":\"day\",\"freshness\":\"1\",\"order_by\":\"views\",\"post_type\":\"post\",\"pid\":\"\",\"exclude\":\"\",\"cat\":\"\",\"taxonomy\":\"category\",\"term_id\":\"\",\"author\":\"\",\"shorten_title\":{\"active\":false,\"length\":0,\"words\":false},\"post-excerpt\":{\"active\":false,\"length\":0,\"keep_format\":false,\"words\":false},\"thumbnail\":{\"active\":true,\"build\":\"predefined\",\"width\":\"240\",\"height\":\"160\"},\"rating\":false,\"stats_tag\":{\"comment_count\":false,\"views\":false,\"author\":false,\"date\":{\"active\":false,\"format\":\"F j, Y\"},\"category\":false,\"taxonomy\":{\"active\":false,\"name\":\"category\"}},\"markup\":{\"custom_html\":true,\"wpp-start\":\"&lt;ul class=&quot;wpp-list wpp-cardview&quot;&gt;\",\"wpp-end\":\"&lt;\\\/ul&gt;\",\"title-start\":\"&lt;h4 class=&quot;widget-title&quot;&gt;\",\"title-end\":\"&lt;\\\/h4&gt;\",\"post-html\":\"&lt;li&gt;{thumb} {title} {stats}&lt;\\\/li&gt;\"},\"theme\":{\"name\":\"\"}}<\/script><div class=\"wpp-shortcode-placeholder\"><\/div><\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a97d24cc9dd1\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row article-image\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"100\" width=\"100\" data-animation=\"fade-in\" src=\"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2023\/06\/2023_03_Max_by_Martine-Severin_01_web.jpg\" alt=\"\"  \/>\r\n         <\/div>\r\n      <\/div><span class=\"vc_figure-caption ccfic-text media-caption\">Max en el Millennium Park de Chicago, Illinois, el 11 de febrero de 2023. <\/span><span class=\"media-credit\">Martine S\u00e9verin para Borderless Magazine<\/span><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a97d24cca2e6\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-2 vc_hidden-sm vc_hidden-xs wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col padding-3-percent inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p>Mi abuela viv\u00eda a unos kil\u00f3metros de nuestra casa. Una tarde fui a su casa y le cont\u00e9 lo que estaba pasando, pero no me crey\u00f3. El comportamiento de mi hermano fue en aumento, as\u00ed que habl\u00e9 con mi t\u00eda, pero me dijo que no se lo contara a nadie. Volv\u00ed a hablar con mi t\u00eda hasta que decidi\u00f3 hacer algo. Llam\u00f3 a mi t\u00edo a Londres y le explic\u00f3 mi situaci\u00f3n.<\/p>\n<p>Mi hermano era peligroso. Mi t\u00edo sugiri\u00f3 ayudarme a comprar un billete a Marruecos, y vol\u00e9 all\u00ed en 2016.<\/p>\n<h2 id=\"building-a-new-life-in-morocco\">Construir una nueva vida en Marruecos<\/h2>\n<p>Empezar de nuevo en Marruecos fue dif\u00edcil, pero mi t\u00edo pudo ayudarme con el alquiler y la comida durante unos tres meses. Pero las cosas se pusieron a\u00fan m\u00e1s dif\u00edciles cuando mi t\u00edo perdi\u00f3 su trabajo en Londres. Necesitaba encontrar una forma de mantenerme. Afortunadamente, me contrataron para trabajar de friegaplatos en un restaurante local. Y busqu\u00e9 un compa\u00f1ero de piso que me ayudara a cubrir gastos. As\u00ed fue como conoc\u00ed a mi primera pareja rom\u00e1ntica.<\/p>\n<p>\u00c9l tambi\u00e9n era de Senegal. Nos conocimos en nuestro lugar de trabajo y m\u00e1s tarde nos fuimos a vivir juntos a un apartamento para ahorrar dinero. Se convirti\u00f3 en mi mejor amigo y m\u00e1s tarde en mi primer amante. Me alegr\u00e9 de encontrar a alguien que entend\u00eda mis creencias. Fue la primera vez que supe qui\u00e9n era. Nos quer\u00edamos tanto que no pod\u00edamos vivir el uno sin el otro.<\/p>\n<\/div>\n\n\n\n<div id=\"fws_6a97d24cca5b2\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone border_bottom_desktop_1px border_color_000000 border_style_solid\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_sep_color_black wpb_content_element vc_separator-has-text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><h4 id=\"read-more-of-our-coverage\">M\u00e1s informaci\u00f3n<\/h4><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t\t\t<div class=\"pk-inline-posts\">\n\t\t\t\n\t\t\t<div class=\"pk-inline-posts-container pk-inline-posts-template-list\"\n\t\t\t\tdata-columns=\"1\">\n\t\t\t\t\t\t<article id=\"post-19214\" class=\"post-19214 post type-post status-publish format-standard has-post-thumbnail category-immigration-policy tag-undocublack\">\n\t\t\t<div class=\"pk-post-outer\">\n\n\t\t\t\t\t\t\t\t<div class=\"pk-post-inner\">\n\t\t\t\t\t<div class=\"entry-thumbnail\">\n\t\t\t\t\t\t<div class=\"pk-overlay pk-overlay-ratio pk-ratio-landscape\">\n\t\t\t\t\t\t\t<div class=\"pk-overlay-background\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/borderlessmag.org\/es\/2023\/05\/26\/black-immigration-united-states-policy\/\" class=\"pk-overlay-link\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2023\/05\/230525-UndocuBlack-1-web.jpg\" class=\"attachment-pk-thumbnail size-pk-thumbnail wp-post-image\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"pk-post-inner\">\n\t\t\t\t\t<header>\n\t\t\t\t\t\t<h3 class=\"pk-title\"><a href=\"https:\/\/borderlessmag.org\/es\/2023\/05\/26\/black-immigration-united-states-policy\/\" rel=\"bookmark\">C\u00f3mo la pol\u00edtica estadounidense impulsa, describe y niega la inmigraci\u00f3n negra<\/a><\/h3>\t\t\t\t\t\t\t<div class=\"pk-post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"pk-meta-author meta-author\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/borderlessmag.org\/es\/author\/jillian-melero\/\" title=\"Ver todas las publicaciones de Jillian Melero\">Jillian Melero<\/a><\/span><\/span>\t\t\t\t\t\t\t\t<span class=\"sep\">-<\/span>\n\t\t\t\t\t\t\t\t<span class=\"pk-meta-date meta-date\"><a href=\"https:\/\/borderlessmag.org\/es\/2023\/05\/26\/black-immigration-united-states-policy\/\" rel=\"bookmark\">26 de mayo de 2023<\/a><\/span>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/header><!-- .entry-header -->\n\t\t\t\t<\/div><!-- .post-inner -->\n\n\t\t\t<\/div><!-- .post-outer -->\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p>Yo era feliz con mi vida en Marruecos, sobre todo con \u00e9l. Hac\u00edamos todo juntos. Cocin\u00e1bamos, trabaj\u00e1bamos, compr\u00e1bamos, com\u00edamos, re\u00edamos o llor\u00e1bamos juntos, pero yo notaba que me ocultaba algo. Nunca me invitaba a sus citas m\u00e9dicas. A veces me ment\u00eda cuando le preguntaba si hab\u00eda ido al m\u00e9dico. Al principio me molestaba y me preguntaba qu\u00e9 pasaba, pero al final lo dej\u00e9. No me enter\u00e9 de los motivos de sus visitas al hospital hasta que recibi\u00f3 una llamada telef\u00f3nica de Senegal comunic\u00e1ndole que su madre hab\u00eda fallecido inesperadamente. Viaj\u00f3 a Senegal para los preparativos del funeral de su madre.<\/p>\n<p>Un s\u00e1bado por la ma\u00f1ana, despu\u00e9s de que se marchara a Senegal, me sent\u00eda aburrida y sola, as\u00ed que decid\u00ed reorganizar la habitaci\u00f3n para mantenerme ocupada. Al hacerlo, descubr\u00ed un malet\u00edn escondido debajo de la cama. Por curiosidad, fui a ver qu\u00e9 hab\u00eda dentro. Fue entonces cuando encontr\u00e9 sus m\u00faltiples historiales m\u00e9dicos y unos cuantos medicamentos que se recetan a un paciente con VIH.<\/p>\n<p>La noticia fue como un golpe en la cara. Me aterroriz\u00f3 descubrir esto sobre mi pareja. Sin embargo, me arm\u00e9 de valor y fui inmediatamente al m\u00e9dico para que me hiciera la prueba del VIH. Por desgracia, el resultado fue positivo. Para m\u00ed fue una tragedia. Estaba destrozada y no sab\u00eda qu\u00e9 hacer. Fotografi\u00e9 todos sus historiales m\u00e9dicos y se los envi\u00e9 en un mensaje pregunt\u00e1ndole por qu\u00e9 los manten\u00eda en secreto. No me dio ninguna explicaci\u00f3n e inmediatamente bloque\u00f3 mi n\u00famero. Desde ese d\u00eda, no he vuelto a saber nada de \u00e9l.<\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 vc_hidden-sm vc_hidden-xs wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t<div class=\"wpb_widgetised_column wpb_content_element\">\n\t\t<div id=\"sidebar\" data-nectar-ss=\"true\" class=\"wpb_wrapper\">\n\t\t\t<div id=\"custom_html-4 1articleright\" class=\"widget_text widget widget_custom_html\"><h3 id=\"wordpress-popular-posts-2\" class=\"widget-title\">Entradas populares de WordPress<\/h3><div class=\"textwidget custom-html-widget\"><h4 id=\"trending-posts-2\" class=\"widget-title\">Tendencias<\/h4><div class=\"wpp-shortcode\"><script type=\"application\/json\" data-id=\"wpp-shortcode-inline-js\">{\"title\":\"Trending Posts\",\"limit\":\"3\",\"offset\":0,\"range\":\"custom\",\"time_quantity\":\"124\",\"time_unit\":\"day\",\"freshness\":\"1\",\"order_by\":\"views\",\"post_type\":\"post\",\"pid\":\"\",\"exclude\":\"\",\"cat\":\"\",\"taxonomy\":\"category\",\"term_id\":\"\",\"author\":\"\",\"shorten_title\":{\"active\":false,\"length\":0,\"words\":false},\"post-excerpt\":{\"active\":false,\"length\":0,\"keep_format\":false,\"words\":false},\"thumbnail\":{\"active\":true,\"build\":\"predefined\",\"width\":\"240\",\"height\":\"160\"},\"rating\":false,\"stats_tag\":{\"comment_count\":false,\"views\":false,\"author\":false,\"date\":{\"active\":false,\"format\":\"F j, Y\"},\"category\":false,\"taxonomy\":{\"active\":false,\"name\":\"category\"}},\"markup\":{\"custom_html\":true,\"wpp-start\":\"&lt;ul class=&quot;wpp-list wpp-cardview&quot;&gt;\",\"wpp-end\":\"&lt;\\\/ul&gt;\",\"title-start\":\"&lt;h4 class=&quot;widget-title&quot;&gt;\",\"title-end\":\"&lt;\\\/h4&gt;\",\"post-html\":\"&lt;li&gt;{thumb} {title} {stats}&lt;\\\/li&gt;\"},\"theme\":{\"name\":\"\"}}<\/script><div class=\"wpp-shortcode-placeholder\"><\/div><\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a97d24ccd0be\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row article-image\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"img-with-aniamtion-wrap center\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"100\" width=\"100\" data-animation=\"fade-in\" src=\"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2023\/06\/2023_03_Max_by_Martine-Severin_04web.jpg\" alt=\"\"  \/>\r\n         <\/div>\r\n      <\/div><span class=\"vc_figure-caption ccfic-text media-caption\">Max en el Millennium Park de Chicago, Illinois, el 11 de febrero de 2023. <\/span><span class=\"media-credit\">Martine S\u00e9verin para Borderless Magazine<\/span><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a97d24ccd47c\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-2 vc_hidden-sm vc_hidden-xs wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col padding-3-percent inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<h2 id=\"starting-over-in-chicago\">Volver a empezar en Chicago<\/h2>\n<p>Unos meses despu\u00e9s de su desaparici\u00f3n, las cosas volvieron a ponerse dif\u00edciles. No pod\u00eda ponerme al d\u00eda con todas las facturas que llegaban. Volv\u00ed a estar como al principio. Pas\u00e9 por mucho estr\u00e9s, depresi\u00f3n y ansiedad intentando averiguar c\u00f3mo pod\u00eda sobrevivir y medicarme. No ten\u00eda ning\u00fan conocimiento sobre el virus.<\/p>\n<p>Frustrada, me puse en contacto con una pareja de la Uni\u00f3n Africana en Marruecos para pedir ayuda. Me remitieron a ACNUR. Me ayudaron con comida, alojamiento y medicamentos desde 2018 hasta 2020. Mientras hac\u00eda todo eso, tambi\u00e9n me dijeron que me trasladar\u00eda a Estados Unidos, donde podr\u00eda estar a salvo.<\/p>\n<p>En Marruecos me discriminaban por ser gay. No pod\u00eda compartir mi verdadera identidad tal como era. Ten\u00eda miedo de ser perseguido. As\u00ed que, como en Senegal, me acosaron muchas veces por actuar como actuaba.<\/p>\n<p>La pandemia de COVID-19 afect\u00f3 a mi proceso de visado, por lo que tard\u00f3 m\u00e1s de lo esperado. Finalmente, consegu\u00ed el visado y me traslad\u00e9 a Chicago en 2020. Estoy muy agradecida por haber encontrado a ACNUR. Son mi mayor sistema de apoyo. Con su ayuda, me han puesto en contacto con m\u00e9dicos para recibir tratamiento y el ACNUR paga actualmente mi medicaci\u00f3n contra el VIH. Gozo de buena salud en este nuevo comienzo.<\/p>\n<p>La vida en EE.UU. sigue siendo un reto, ya que intento desenvolverme en el nuevo sistema, pero me siento segura; tengo amigos con creencias comunes. A veces me pongo triste; mi madre muri\u00f3 el a\u00f1o pasado y no pude ir por lo que dir\u00eda mi familia. Mi familia me rechaz\u00f3 por lo que soy. Ya no puedo volver a mi pa\u00eds de origen.<\/p>\n<p>Aqu\u00ed los tr\u00e1mites de inmigraci\u00f3n son eternos. Siempre he so\u00f1ado con ser azafata de vuelo, pero no puedo ir a la universidad sin la documentaci\u00f3n adecuada. Por ahora, trabajo de camarera en un restaurante. La vida no ha sido f\u00e1cil desde que llegu\u00e9 a Chicago. Pero estoy agradecida de que no me juzguen por lo que soy y de contar con el apoyo del ACNUR. Aqu\u00ed estoy feliz y segura.<\/p>\n<\/div>\n\n\n\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_30 vc_sep_pos_align_center vc_sep_color_black wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p><em>Este reportaje se ha realizado siguiendo el m\u00e9todo colaborativo de Borderless Magazine.  Para saber c\u00f3mo creamos historias como \u00e9sta, consulte nuestro <a href=\"https:\/\/borderlessmag.org\/es\/segun-el-metodo\/\">explicaci\u00f3n visual<\/a>.<\/em><\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 vc_hidden-sm vc_hidden-xs wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t<div class=\"wpb_widgetised_column wpb_content_element\">\n\t\t<div id=\"sidebar\" data-nectar-ss=\"true\" class=\"wpb_wrapper\">\n\t\t\t<div id=\"custom_html-4 1articleright\" class=\"widget_text widget widget_custom_html\"><h3 id=\"wordpress-popular-posts-3\" class=\"widget-title\">Entradas populares de WordPress<\/h3><div class=\"textwidget custom-html-widget\"><h4 id=\"trending-posts-3\" class=\"widget-title\">Tendencias<\/h4><div class=\"wpp-shortcode\"><script type=\"application\/json\" data-id=\"wpp-shortcode-inline-js\">{\"title\":\"Trending Posts\",\"limit\":\"3\",\"offset\":0,\"range\":\"custom\",\"time_quantity\":\"124\",\"time_unit\":\"day\",\"freshness\":\"1\",\"order_by\":\"views\",\"post_type\":\"post\",\"pid\":\"\",\"exclude\":\"\",\"cat\":\"\",\"taxonomy\":\"category\",\"term_id\":\"\",\"author\":\"\",\"shorten_title\":{\"active\":false,\"length\":0,\"words\":false},\"post-excerpt\":{\"active\":false,\"length\":0,\"keep_format\":false,\"words\":false},\"thumbnail\":{\"active\":true,\"build\":\"predefined\",\"width\":\"240\",\"height\":\"160\"},\"rating\":false,\"stats_tag\":{\"comment_count\":false,\"views\":false,\"author\":false,\"date\":{\"active\":false,\"format\":\"F j, Y\"},\"category\":false,\"taxonomy\":{\"active\":false,\"name\":\"category\"}},\"markup\":{\"custom_html\":true,\"wpp-start\":\"&lt;ul class=&quot;wpp-list wpp-cardview&quot;&gt;\",\"wpp-end\":\"&lt;\\\/ul&gt;\",\"title-start\":\"&lt;h4 class=&quot;widget-title&quot;&gt;\",\"title-end\":\"&lt;\\\/h4&gt;\",\"post-html\":\"&lt;li&gt;{thumb} {title} {stats}&lt;\\\/li&gt;\"},\"theme\":{\"name\":\"\"}}<\/script><div class=\"wpp-shortcode-placeholder\"><\/div><\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Max naci\u00f3 y creci\u00f3 en Senegal. Pero tras a\u00f1os de sufrir penurias econ\u00f3micas y abusos sexuales, fue expulsado de su familia.<\/p>","protected":false},"author":139,"featured_media":19341,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[28],"tags":[465],"coauthors":[466],"class_list":["post-19346","post","type-post","status-publish","format-standard","has-post-thumbnail","category-as-told-to","tag-maxsenegal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Black Immigrants Today: Max &#8211; Borderless<\/title>\n<meta name=\"description\" content=\"Max was born and raised in Senegal. But after years of suffering economic hardship and sexual abuse, he was cast out of his family.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/borderlessmag.org\/es\/2023\/06\/05\/inmigrantes-negros-hoy-max-senegal-marruecos\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Max &#8211; Borderless Magazine NFP\" \/>\n<meta property=\"og:description\" content=\"Max &#8211; Borderless Magazine NFP\" \/>\n<meta property=\"og:url\" content=\"https:\/\/borderlessmag.org\/es\/2023\/06\/05\/inmigrantes-negros-hoy-max-senegal-marruecos\/\" \/>\n<meta property=\"og:site_name\" content=\"Borderless Magazine NFP\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BorderlessMagazine\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-05T15:27:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T14:04:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2023\/06\/2023_03_Max_by_Martine-Severin_03R2-1web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jillian Melero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vida Opoku\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Jillian Melero\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/2023\\\/06\\\/05\\\/black-immigrants-today-max-senegal-morocco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/2023\\\/06\\\/05\\\/black-immigrants-today-max-senegal-morocco\\\/\"},\"author\":{\"name\":\"Vida Opoku\",\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#\\\/schema\\\/person\\\/a13aa097ea42b5a7822f09f6edff64f1\"},\"headline\":\"Max\",\"datePublished\":\"2023-06-05T15:27:30+00:00\",\"dateModified\":\"2025-10-08T14:04:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/2023\\\/06\\\/05\\\/black-immigrants-today-max-senegal-morocco\\\/\"},\"wordCount\":3183,\"publisher\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/2023\\\/06\\\/05\\\/black-immigrants-today-max-senegal-morocco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borderlessmag.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/2023_03_Max_by_Martine-Severin_03R2-1web.jpg\",\"keywords\":[\"maxsenegal\"],\"articleSection\":[\"As Told To\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/es\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/2023\\\/06\\\/05\\\/black-immigrants-today-max-senegal-morocco\\\/\",\"url\":\"https:\\\/\\\/borderlessmag.org\\\/2023\\\/06\\\/05\\\/black-immigrants-today-max-senegal-morocco\\\/\",\"name\":\"Black Immigrants Today: Max &#8211; Borderless\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/2023\\\/06\\\/05\\\/black-immigrants-today-max-senegal-morocco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/2023\\\/06\\\/05\\\/black-immigrants-today-max-senegal-morocco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borderlessmag.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/2023_03_Max_by_Martine-Severin_03R2-1web.jpg\",\"datePublished\":\"2023-06-05T15:27:30+00:00\",\"dateModified\":\"2025-10-08T14:04:29+00:00\",\"description\":\"Max was born and raised in Senegal. But after years of suffering economic hardship and sexual abuse, he was cast out of his family.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/borderlessmag.org\\\/2023\\\/06\\\/05\\\/black-immigrants-today-max-senegal-morocco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/2023\\\/06\\\/05\\\/black-immigrants-today-max-senegal-morocco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/borderlessmag.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/2023_03_Max_by_Martine-Severin_03R2-1web.jpg\",\"contentUrl\":\"https:\\\/\\\/borderlessmag.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/2023_03_Max_by_Martine-Severin_03R2-1web.jpg\",\"caption\":\"Max in Millennium Park in Chicago, Ill., Feb. 11, 2023.\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#website\",\"url\":\"https:\\\/\\\/borderlessmag.org\\\/\",\"name\":\"Borderless Magazine NFP\",\"description\":\"Stories about immigration and immigrants\",\"publisher\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#organization\"},\"alternateName\":\"Borderless\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/borderlessmag.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#organization\",\"name\":\"Borderless Magazine NFP\",\"alternateName\":\"Borderless Mag\",\"url\":\"https:\\\/\\\/borderlessmag.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/borderlessmag.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/BorderlessLogo_main_square.jpg\",\"contentUrl\":\"https:\\\/\\\/borderlessmag.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/BorderlessLogo_main_square.jpg\",\"width\":696,\"height\":696,\"caption\":\"Borderless Magazine NFP\"},\"image\":{\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BorderlessMagazine\",\"https:\\\/\\\/www.instagram.com\\\/borderless_mag\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@borderless_mag\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/borderlessmag.org\\\/#\\\/schema\\\/person\\\/a13aa097ea42b5a7822f09f6edff64f1\",\"name\":\"Vida Opoku\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83e52f1362d2c9e6b997af6cfa88e333c7d46fe7f4ab05d99ac980746f474d21?s=96&d=mm&r=g20f768c20def3929baec5fb15a9a0aff\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83e52f1362d2c9e6b997af6cfa88e333c7d46fe7f4ab05d99ac980746f474d21?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/83e52f1362d2c9e6b997af6cfa88e333c7d46fe7f4ab05d99ac980746f474d21?s=96&d=mm&r=g\",\"caption\":\"Vida Opoku\"},\"url\":\"https:\\\/\\\/borderlessmag.org\\\/es\\\/author\\\/vida-opoku\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Inmigrantes negros hoy: Max - Sin fronteras","description":"Max naci\u00f3 y creci\u00f3 en Senegal. Pero tras a\u00f1os de sufrir penurias econ\u00f3micas y abusos sexuales, fue expulsado de su familia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/borderlessmag.org\/es\/2023\/06\/05\/inmigrantes-negros-hoy-max-senegal-marruecos\/","og_locale":"es_MX","og_type":"article","og_title":"Max &#8211; Borderless Magazine NFP","og_description":"Max &#8211; Borderless Magazine NFP","og_url":"https:\/\/borderlessmag.org\/es\/2023\/06\/05\/inmigrantes-negros-hoy-max-senegal-marruecos\/","og_site_name":"Borderless Magazine NFP","article_publisher":"https:\/\/www.facebook.com\/BorderlessMagazine","article_published_time":"2023-06-05T15:27:30+00:00","article_modified_time":"2025-10-08T14:04:29+00:00","og_image":[{"url":"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2023\/06\/2023_03_Max_by_Martine-Severin_03R2-1web.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"Jillian Melero","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Vida Opoku","Tiempo de lectura":"16 minutos","Written by":"Jillian Melero"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/borderlessmag.org\/2023\/06\/05\/black-immigrants-today-max-senegal-morocco\/#article","isPartOf":{"@id":"https:\/\/borderlessmag.org\/2023\/06\/05\/black-immigrants-today-max-senegal-morocco\/"},"author":{"name":"Vida Opoku","@id":"https:\/\/borderlessmag.org\/#\/schema\/person\/a13aa097ea42b5a7822f09f6edff64f1"},"headline":"Max","datePublished":"2023-06-05T15:27:30+00:00","dateModified":"2025-10-08T14:04:29+00:00","mainEntityOfPage":{"@id":"https:\/\/borderlessmag.org\/2023\/06\/05\/black-immigrants-today-max-senegal-morocco\/"},"wordCount":3183,"publisher":{"@id":"https:\/\/borderlessmag.org\/#organization"},"image":{"@id":"https:\/\/borderlessmag.org\/2023\/06\/05\/black-immigrants-today-max-senegal-morocco\/#primaryimage"},"thumbnailUrl":"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2023\/06\/2023_03_Max_by_Martine-Severin_03R2-1web.jpg","keywords":["maxsenegal"],"articleSection":["As Told To"],"inLanguage":"es","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/borderlessmag.org\/es\/#organization"}},{"@type":"WebPage","@id":"https:\/\/borderlessmag.org\/2023\/06\/05\/black-immigrants-today-max-senegal-morocco\/","url":"https:\/\/borderlessmag.org\/2023\/06\/05\/black-immigrants-today-max-senegal-morocco\/","name":"Inmigrantes negros hoy: Max - Sin fronteras","isPartOf":{"@id":"https:\/\/borderlessmag.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/borderlessmag.org\/2023\/06\/05\/black-immigrants-today-max-senegal-morocco\/#primaryimage"},"image":{"@id":"https:\/\/borderlessmag.org\/2023\/06\/05\/black-immigrants-today-max-senegal-morocco\/#primaryimage"},"thumbnailUrl":"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2023\/06\/2023_03_Max_by_Martine-Severin_03R2-1web.jpg","datePublished":"2023-06-05T15:27:30+00:00","dateModified":"2025-10-08T14:04:29+00:00","description":"Max naci\u00f3 y creci\u00f3 en Senegal. Pero tras a\u00f1os de sufrir penurias econ\u00f3micas y abusos sexuales, fue expulsado de su familia.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/borderlessmag.org\/2023\/06\/05\/black-immigrants-today-max-senegal-morocco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/borderlessmag.org\/2023\/06\/05\/black-immigrants-today-max-senegal-morocco\/#primaryimage","url":"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2023\/06\/2023_03_Max_by_Martine-Severin_03R2-1web.jpg","contentUrl":"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2023\/06\/2023_03_Max_by_Martine-Severin_03R2-1web.jpg","caption":"Max in Millennium Park in Chicago, Ill., Feb. 11, 2023."},{"@type":"WebSite","@id":"https:\/\/borderlessmag.org\/#website","url":"https:\/\/borderlessmag.org\/","name":"Revista Borderless NFP","description":"Historias sobre inmigraci\u00f3n e inmigrantes","publisher":{"@id":"https:\/\/borderlessmag.org\/#organization"},"alternateName":"Borderless","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/borderlessmag.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/borderlessmag.org\/#organization","name":"Revista Borderless NFP","alternateName":"Borderless Mag","url":"https:\/\/borderlessmag.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/borderlessmag.org\/#\/schema\/logo\/image\/","url":"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2025\/08\/BorderlessLogo_main_square.jpg","contentUrl":"https:\/\/borderlessmag.org\/wordpress\/wp-content\/uploads\/2025\/08\/BorderlessLogo_main_square.jpg","width":696,"height":696,"caption":"Borderless Magazine NFP"},"image":{"@id":"https:\/\/borderlessmag.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BorderlessMagazine","https:\/\/www.instagram.com\/borderless_mag\/","https:\/\/www.tiktok.com\/@borderless_mag"]},{"@type":"Person","@id":"https:\/\/borderlessmag.org\/#\/schema\/person\/a13aa097ea42b5a7822f09f6edff64f1","name":"Vida Opoku","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/83e52f1362d2c9e6b997af6cfa88e333c7d46fe7f4ab05d99ac980746f474d21?s=96&d=mm&r=g20f768c20def3929baec5fb15a9a0aff","url":"https:\/\/secure.gravatar.com\/avatar\/83e52f1362d2c9e6b997af6cfa88e333c7d46fe7f4ab05d99ac980746f474d21?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/83e52f1362d2c9e6b997af6cfa88e333c7d46fe7f4ab05d99ac980746f474d21?s=96&d=mm&r=g","caption":"Vida Opoku"},"url":"https:\/\/borderlessmag.org\/es\/author\/vida-opoku\/"}]}},"cc_featured_image_caption":{"caption_text":"Max in Millennium Park in Chicago, Ill., Feb. 11, 2023.","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/posts\/19346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/users\/139"}],"replies":[{"embeddable":true,"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/comments?post=19346"}],"version-history":[{"count":1,"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/posts\/19346\/revisions"}],"predecessor-version":[{"id":29656,"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/posts\/19346\/revisions\/29656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/media\/19341"}],"wp:attachment":[{"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/media?parent=19346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/categories?post=19346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/tags?post=19346"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/borderlessmag.org\/es\/wp-json\/wp\/v2\/coauthors?post=19346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}